{"id":37,"date":"2024-02-19T10:37:35","date_gmt":"2024-02-19T10:37:35","guid":{"rendered":"http:\/\/luminous-horizon.eu\/?page_id=37"},"modified":"2026-05-04T19:43:12","modified_gmt":"2026-05-04T17:43:12","slug":"news-events","status":"publish","type":"page","link":"http:\/\/luminous-horizon.eu\/index.php\/news-events\/","title":{"rendered":"News &#038; Events"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" style=\"padding-top:50px;padding-right:550px;padding-bottom:0px;padding-left:0px\">News &amp; Events<\/h2>\n\n\n\n<div class=\"wp-block-group alignfull has-background has-global-padding is-layout-constrained wp-container-core-group-is-layout-0022af58 wp-block-group-is-layout-constrained\" style=\"background-color:#ffffff;margin-top:0;margin-bottom:0;padding-top:100px;padding-right:20px;padding-bottom:100px;padding-left:20px\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1126\" src=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/05\/shared-image-3.jpg\" alt=\"\" class=\"wp-image-952\" style=\"object-fit:cover;width:417px;height:283px\" srcset=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/05\/shared-image-3.jpg 2000w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/05\/shared-image-3-300x169.jpg 300w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/05\/shared-image-3-1024x577.jpg 1024w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/05\/shared-image-3-768x432.jpg 768w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/05\/shared-image-3-1536x865.jpg 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-1\" style=\"color:#07277c;font-size:clamp(18.434px, 1.152rem + ((1vw - 3.2px) * 1.201), 29px);\"><strong>General Assembly (Lavigny, Switzerland)<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.568), 19px);\"><em>26.03.2026 \u201327.03.2026<\/em><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.341), 17px);\">The LUMINOUS project held its General Assembly in Lavigny, Switzerland, hosted at\u00a0\u2026\u00a0<a href=\"https:\/\/luminous-horizon.eu\/index.php\/general-assembly-lavigny-switzerland\/\">Read more<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/Afzal-1-3-scaled.jpg\" alt=\"\" class=\"wp-image-933\" style=\"object-fit:cover;width:417px;height:283px\" srcset=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/Afzal-1-3-scaled.jpg 2560w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/Afzal-1-3-300x225.jpg 300w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/Afzal-1-3-1024x768.jpg 1024w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/Afzal-1-3-768x576.jpg 768w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/Afzal-1-3-1536x1152.jpg 1536w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/Afzal-1-3-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-2\" style=\"color:#07277c;font-size:clamp(18.434px, 1.152rem + ((1vw - 3.2px) * 1.201), 29px);\"><strong>SIGGRAPH Asia 2025 (Hong Kong)<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.568), 19px);\"><em>15.12.2025 \u201318.12.2025<\/em><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.341), 17px);\">At the 18th ACM SIGGRAPH Conference and Exhibition on Computer Graphics and Interactive&nbsp;\u2026&nbsp;<a href=\"https:\/\/luminous-horizon.eu\/index.php\/siggraph-asia-2025\/\">Read more<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1546\" height=\"1600\" src=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/1000104253.jpg\" alt=\"\" class=\"wp-image-902\" style=\"object-fit:cover;width:417px;height:283px\" srcset=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/1000104253.jpg 1546w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/1000104253-290x300.jpg 290w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/1000104253-989x1024.jpg 989w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/1000104253-768x795.jpg 768w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/1000104253-1484x1536.jpg 1484w\" sizes=\"auto, (max-width: 1546px) 100vw, 1546px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-3\" style=\"color:#07277c;font-size:clamp(18.434px, 1.152rem + ((1vw - 3.2px) * 1.201), 29px);\"><strong>UnitedXR Europe 2025 (Brussels, Belgium)<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.568), 19px);\"><em>08.12.2025 &#8211; 10.12.2025<\/em><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.341), 17px);\">We were proud to represent LUMINOUS at UnitedXR Europe 2025, connecting with&#8230; <a href=\"https:\/\/luminous-horizon.eu\/index.php\/unitedxr-europe-2025-brussels-belgium\/\" data-type=\"page\" data-id=\"657\">Read more<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/IMG_8594-1-scaled.jpg\" alt=\"\" class=\"wp-image-897\" srcset=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/IMG_8594-1-scaled.jpg 2560w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/IMG_8594-1-300x225.jpg 300w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/IMG_8594-1-1024x768.jpg 1024w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/IMG_8594-1-768x576.jpg 768w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/IMG_8594-1-1536x1152.jpg 1536w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/01\/IMG_8594-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-4\" style=\"color:#07277c;font-size:clamp(18.434px, 1.152rem + ((1vw - 3.2px) * 1.201), 29px);\"><strong>General Assembly (Berlin, Germany)<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.568), 19px);\"><em>16.10.2025 &#8211; 17.10.2025<\/em><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.341), 17px);\">We recently held a highly productive General Assembly meeting in&#8230; <a href=\"https:\/\/luminous-horizon.eu\/index.php\/general-assembly-berlin-germany\/\" data-type=\"page\" data-id=\"657\">Read more<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"884\" src=\"https:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/1757423541210-2.jpg\" alt=\"\" class=\"wp-image-935\" srcset=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/1757423541210-2.jpg 2048w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/1757423541210-2-300x129.jpg 300w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/1757423541210-2-1024x442.jpg 1024w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/1757423541210-2-768x332.jpg 768w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2026\/02\/1757423541210-2-1536x663.jpg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-5\" style=\"color:#07277c;font-size:clamp(18.434px, 1.152rem + ((1vw - 3.2px) * 1.201), 29px);\"><strong>EuroXR 2025 (Winterthur, Switzerland)<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.568), 19px);\"><em>03.09.2025 \u2013 05.09.2025<\/em><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.341), 17px);\">At the EuroXR 2025, LUMINOUS once again made a strong contribution to Europe\u2019s extended-reality,\u2026 <a href=\"https:\/\/luminous-horizon.eu\/index.php\/euroxr-2025\/\" data-type=\"page\" data-id=\"914\">Read more<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1218\" src=\"https:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/04\/1743768960941.jpeg\" alt=\"\" class=\"wp-image-655\" srcset=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/04\/1743768960941.jpeg 2048w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/04\/1743768960941-300x178.jpeg 300w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/04\/1743768960941-1024x609.jpeg 1024w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/04\/1743768960941-768x457.jpeg 768w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/04\/1743768960941-1536x914.jpeg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-6\" style=\"color:#07277c;font-size:clamp(18.434px, 1.152rem + ((1vw - 3.2px) * 1.201), 29px);\"><strong>General Assembly (Dublin, Ireland)<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.568), 19px);\"><em>03.04.2025 &#8211; 04.04.202<\/em>5<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.341), 17px);\">The Luminous team wrapped up another successful General Assembly meeting, &#8230; <a href=\"https:\/\/luminous-horizon.eu\/index.php\/general-assembly-dublin-ireland\/\" data-type=\"page\" data-id=\"657\">Read more<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/06\/EuroXR.jpeg\" alt=\"\" class=\"wp-image-675\" srcset=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/06\/EuroXR.jpeg 1600w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/06\/EuroXR-300x225.jpeg 300w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/06\/EuroXR-1024x768.jpeg 1024w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/06\/EuroXR-768x576.jpeg 768w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/06\/EuroXR-1536x1152.jpeg 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-7\" style=\"color:#07277c;font-size:clamp(18.434px, 1.152rem + ((1vw - 3.2px) * 1.201), 29px);\"><strong>EuroXR 2024 (Athens, Greece)<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.568), 19px);\"><em>27.11.2024 &#8211; 29.11.2024<\/em><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.341), 17px);\">At the 21 st EuroXR International Conference 2024 in Athens, LUMINOUS featured prominently.. <a href=\"https:\/\/luminous-horizon.eu\/index.php\/euroxr-2024\/\" data-type=\"page\" data-id=\"642\">Read more<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1280\" src=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/02\/RICOH_THETA_group_photo_Equi-scaled.jpeg\" alt=\"\" class=\"wp-image-643\" srcset=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/02\/RICOH_THETA_group_photo_Equi-scaled.jpeg 2560w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/02\/RICOH_THETA_group_photo_Equi-300x150.jpeg 300w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/02\/RICOH_THETA_group_photo_Equi-1024x512.jpeg 1024w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/02\/RICOH_THETA_group_photo_Equi-768x384.jpeg 768w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/02\/RICOH_THETA_group_photo_Equi-1536x768.jpeg 1536w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/02\/RICOH_THETA_group_photo_Equi-2048x1024.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-8\" style=\"color:#07277c;font-size:clamp(18.434px, 1.152rem + ((1vw - 3.2px) * 1.201), 29px);\"><strong>General Assembly (Athens, Greece)<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.568), 19px);\"><em>14.11.2024 &#8211; 15.11.2024<\/em><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.341), 17px);\">The Luminous General Assembly took place in Athens on November 14-15, 2024, bringing together&#8230; <a href=\"https:\/\/luminous-horizon.eu\/index.php\/general-assembly-athens-greece\/\" data-type=\"page\" data-id=\"642\">Read more<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"481\" src=\"https:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/02\/Web3D.jpg\" alt=\"\" class=\"wp-image-627\" srcset=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/02\/Web3D.jpg 640w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2025\/02\/Web3D-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-9\" style=\"color:#07277c;font-size:clamp(18.434px, 1.152rem + ((1vw - 3.2px) * 1.201), 29px);\"><strong>Luminous at Web3D 2024: Advancing the Future of Extended Reality<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.568), 19px);\"><em>25.09.2024 &#8211; 27.09.2024<\/em><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.341), 17px);\">Web3D 2024 was held from September 25\u201327 at the CCG\/ZGDV Institute, Azur\u00e9m Campus, Guimar\u00e3es, Portugal. This prestigious event brought together experts, researchers, and industry leaders to explore the latest advancements in&#8230; <a href=\"https:\/\/luminous-horizon.eu\/index.php\/luminous-at-web3d-2024-advancing-the-future-of-extended-reality\/\" data-type=\"page\" data-id=\"632\">Read more<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2024\/06\/1000145307.jpg\" alt=\"\" class=\"wp-image-586\" srcset=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2024\/06\/1000145307.jpg 1600w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2024\/06\/1000145307-300x169.jpg 300w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2024\/06\/1000145307-1024x576.jpg 1024w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2024\/06\/1000145307-768x432.jpg 768w, http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2024\/06\/1000145307-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-10\" style=\"color:#07277c;font-size:clamp(18.434px, 1.152rem + ((1vw - 3.2px) * 1.201), 29px);\"><strong><strong>General Assembly at Vicomtech<\/strong><\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.568), 19px);\"><em>09.04.2024 &#8211; 10.04.2024<\/em><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.341), 17px);\">On the 9th and 10th of April, a plenary meeting took place at Vicomtech in San Sabastian, Spain, to discuss the goal of Luminous and agree on how different partners&#8230; <a href=\"https:\/\/luminous-horizon.eu\/index.php\/553-2\/\" data-type=\"page\" data-id=\"553\">Read more<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1323\" src=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2024\/02\/Panel.jpg-1.webp\" alt=\"\" class=\"wp-image-368\" style=\"width:387px;height:auto\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-11\" style=\"color:#07277c;font-size:clamp(18.434px, 1.152rem + ((1vw - 3.2px) * 1.201), 29px);\"><strong>Panel discussion participation during \u2018Research to Reality: Digital Solutions to European Challenges\u2019<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.568), 19px);\"><em>12.02.2024<\/em><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.341), 17px);\">On February 5th &amp; 6th, organized under the Belgian presidency in cooperation with the European Commission, this year\u2019s \u2018Research to Reality: Digital Solutions to European Challenges\u2019 event was hosted in Brussels. This even promises&#8230; <a href=\"http:\/\/luminous-horizon.eu\/index.php\/panel-discussion-participation-during-research-to-reality-digital-solutions-to-european-challenges\/\" data-type=\"page\" data-id=\"371\">Read More<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1227\" src=\"http:\/\/luminous-horizon.eu\/wp-content\/uploads\/2024\/03\/DSC047072.jpg\" alt=\"\" class=\"wp-image-412\" style=\"width:387px;height:auto\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-12\" style=\"color:#07277c;font-size:clamp(18.434px, 1.152rem + ((1vw - 3.2px) * 1.201), 29px);\"><strong>Kick-off Meeting for Luminous<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.568), 19px);\"><em>16.01.2024 &#8211; 17.01.2024<\/em><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.341), 17px);\">On the 16th &amp; 17th of January, 2024, a meeting took place at DFKI in Kaiserslautern to kick-off the European research project Luminous. The kickoff meeting was attended&#8230; <a href=\"http:\/\/luminous-horizon.eu\/index.php\/kick-off-meeting\/\" data-type=\"page\" data-id=\"378\">Read more<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>News &amp; Events General Assembly (Lavigny, Switzerland) 26.03.2026 \u201327.03.2026 The LUMINOUS project held its General Assembly in Lavigny, Switzerland, hosted at\u00a0\u2026\u00a0Read more SIGGRAPH Asia 2025 (Hong Kong) 15.12.2025 \u201318.12.2025 At the 18th ACM SIGGRAPH Conference and Exhibition on Computer Graphics and Interactive&nbsp;\u2026&nbsp;Read more UnitedXR Europe 2025 (Brussels, Belgium) 08.12.2025 &#8211; 10.12.2025 We were proud to [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-37","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/luminous-horizon.eu\/index.php\/wp-json\/wp\/v2\/pages\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/luminous-horizon.eu\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/luminous-horizon.eu\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/luminous-horizon.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/luminous-horizon.eu\/index.php\/wp-json\/wp\/v2\/comments?post=37"}],"version-history":[{"count":45,"href":"http:\/\/luminous-horizon.eu\/index.php\/wp-json\/wp\/v2\/pages\/37\/revisions"}],"predecessor-version":[{"id":953,"href":"http:\/\/luminous-horizon.eu\/index.php\/wp-json\/wp\/v2\/pages\/37\/revisions\/953"}],"wp:attachment":[{"href":"http:\/\/luminous-horizon.eu\/index.php\/wp-json\/wp\/v2\/media?parent=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}